{"id":70,"date":"2023-08-16T07:38:57","date_gmt":"2023-08-16T07:38:57","guid":{"rendered":"https:\/\/clinicadelpievara.es\/?page_id=70"},"modified":"2025-12-26T11:41:33","modified_gmt":"2025-12-26T11:41:33","slug":"inicio-2","status":"publish","type":"page","link":"https:\/\/clinicadelpievara.es\/en\/","title":{"rendered":"HOME"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bboff|phone\u00bb admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.21.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb120deg\u00bb background_color_gradient_stops=\u00bb#1664ac 0%|rgba(42,63,201,0.77) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bb#3d0dad\u00bb background_color_gradient_end=\u00bbrgba(42,63,201,0.77)\u00bb background_image=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/Sin-titulo-Banner-horizontal.png\u00bb custom_padding=\u00bb10vw|0px|10vw|0px|true|false\u00bb custom_padding_tablet=\u00bb120px||120px||true\u00bb custom_padding_phone=\u00bb60px||60px||true\u00bb border_color_all=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; border_color_all=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bbMontserrat||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.5em\u00bb header_font=\u00bbMontserrat|800|||||||\u00bb header_font_size=\u00bb90px\u00bb header_line_height=\u00bb1.2em\u00bb background_layout=\u00bbdark\u00bb max_width_tablet=\u00bb\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb28px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb]<\/p>\n<h1>CL\u00cdNICA DEL PIE VARA<\/h1>\n<p><span>Caminando juntos hacia la salud de tus pies: Cuidado, cercan\u00eda y confianza en cada paso.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/clinicadelpievara.es\/contacto\/\u00bb button_text=\u00bbPEDIR CITA\u00bb _builder_version=\u00bb4.21.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#103048&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb5px\u00bb button_letter_spacing=\u00bb2px\u00bb button_font=\u00bbMontserrat|600||on|||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#7a9eff\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb admin_label=\u00bbContact Info\u00bb _builder_version=\u00bb4.16&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bb#ffffff 0%|#eff9ff 100%\u00bb background_color_gradient_start=\u00bb#ffffff\u00bb background_color_gradient_end=\u00bb#eff9ff\u00bb background_image=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/health-clinic-02.png\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbbottom_center\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb parallax__hover=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbUBICACI\u00d3N\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe081;||divi||400&#8243; icon_color=\u00bb#1664ac\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.21.0&#8243; header_font=\u00bbWork Sans|600||on|||||\u00bb header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb2px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bbWork Sans||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.8em\u00bb animation=\u00bboff\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb body_line_height__hover=\u00bb1.7em\u00bb body_line_height__hover_enabled=\u00bb1.7em\u00bb body_font_size__hover=\u00bb14px\u00bb body_font_size__hover_enabled=\u00bb14px\u00bb]<\/p>\n<p><span>Av. Constituci\u00f3n de 1812, n\u00ba1, Entreplanta B, 11008 C\u00e1diz<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/www.google.com\/maps?sca_esv=560946880&#038;rlz=1C1YTUH_esES1062ES1062&#038;output=search&#038;q=clinica+del+pie+vara&#038;source=lnms&#038;entry=mc&#038;sa=X&#038;sqi=2&#038;ved=2ahUKEwjFkvq3xYGBAxXfQvEDHWnnCigQ0pQJegQIDBAB\u00bb button_text=\u00bbVER DIRECCI\u00d3N\u00bb _builder_version=\u00bb4.21.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#1664ac\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb5px\u00bb button_letter_spacing=\u00bb2px\u00bb button_font=\u00bbWork Sans|600||on|||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb10px|30px|10px|30px|true|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#82ddb0&#8243;][\/et_pb_button][et_pb_image src=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/Sin-titulo-Banner-horizontal-1.png\u00bb title_text=\u00bbSin t\u00edtulo (Banner (horizontal)) (1)\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.21.0&#8243; max_width_tablet=\u00bb400px\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|tablet\u00bb custom_margin=\u00bb130px|||-10vw\u00bb custom_margin_tablet=\u00bb0px|||0vw\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbfade\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb parallax__hover=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner padding_top_bottom_link_1=\u00bbtrue\u00bb padding_left_right_link_1=\u00bbtrue\u00bb _builder_version=\u00bb4.21.0&#8243; background_color=\u00bb#103048&#8243; custom_margin=\u00bb-15vw||\u00bb animation_style=\u00bbflip\u00bb border_radii=\u00bb|30px||30px|\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb42px\u00bb box_shadow_blur=\u00bb108px\u00bb box_shadow_spread=\u00bb-26px\u00bb box_shadow_color=\u00bbrgba(98,222,157,0.64)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb padding_bottom__hover=\u00bb40px\u00bb padding_left__hover=\u00bb40px\u00bb padding_right__hover=\u00bb40px\u00bb padding_top__hover=\u00bb40px\u00bb parallax__hover=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bbMontserrat||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bbMontserrat||||||||\u00bb header_2_font=\u00bbMontserrat|700|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.4em\u00bb background_layout=\u00bbdark\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb]<\/p>\n<h2>CONTACTO<\/h2>\n<p><span>Estamos aqu\u00ed para cuidar de la salud de tus pies. Cont\u00e1ctanos y da el primer paso hacia el bienestar podol\u00f3gico.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bbLL\u00c1MANOS\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#ffffff\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.21.0&#8243; header_font=\u00bbWork Sans|600||on|||||\u00bb header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb2px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bbWork Sans||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.5em\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb||40px\u00bb animation=\u00bboff\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb body_font_size__hover=\u00bb14px\u00bb body_font_size__hover_enabled=\u00bb14px\u00bb]<\/p>\n<p><a data-dtype=\"d3ph\" data-local-attribute=\"d3ph\" jscontroller=\"LWZElb\" href=\"tel:+34956252545\" jsdata=\"QKGTRc;_;ASzCk0\" jsaction=\"rcuQ6b:npT2md;F75qrd\" data-ved=\"2ahUKEwivn4yx3OCAAxV7TKQEHUWKAegQkAgoAHoECDUQAw\"><span aria-label=\"Llamar al n\u00famero de tel\u00e9fono 956 25 25 45\">956 25 25 45<\/span><\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/clinicadelpievara.es\/contacto\/\u00bb button_text=\u00bbPEDIR CITA\u00bb _builder_version=\u00bb4.21.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bbrgba(255,255,255,0.12)\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb5px\u00bb button_letter_spacing=\u00bb2px\u00bb button_font=\u00bbWork Sans|600||on|||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb10px|30px|10px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover=\u00bbrgba(255,255,255,0.24)\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb parallax__hover=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbWork Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbWork Sans|700|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.4em\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb header_font_size__hover=\u00bb30px\u00bb header_font_size__hover_enabled=\u00bb30px\u00bb header_letter_spacing__hover=\u00bb0px\u00bb header_letter_spacing__hover_enabled=\u00bb0px\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb][\/et_pb_text][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbWork Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbWork Sans|700|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.4em\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb header_font_size__hover=\u00bb30px\u00bb header_font_size__hover_enabled=\u00bb30px\u00bb header_letter_spacing__hover=\u00bb0px\u00bb header_letter_spacing__hover_enabled=\u00bb0px\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb][\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout Us\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#eff9ff\u00bb custom_width_px__hover=\u00bb1080px\u00bb custom_width_px__hover_enabled=\u00bb1080px\u00bb custom_width_percent__hover=\u00bb80%\u00bb custom_width_percent__hover_enabled=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb gutter_width__hover=\u00bb3&#8243; gutter_width__hover_enabled=\u00bb3&#8243; parallax_1__hover=\u00bboff\u00bb parallax_1__hover_enabled=\u00bboff\u00bb parallax_2__hover=\u00bboff\u00bb parallax_2__hover_enabled=\u00bboff\u00bb parallax_3__hover=\u00bboff\u00bb parallax_3__hover_enabled=\u00bboff\u00bb parallax_method_1__hover=\u00bbon\u00bb parallax_method_1__hover_enabled=\u00bbon\u00bb parallax_method_2__hover=\u00bbon\u00bb parallax_method_2__hover_enabled=\u00bbon\u00bb parallax_method_3__hover=\u00bbon\u00bb parallax_method_3__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb inner_shadow__hover=\u00bboff\u00bb inner_shadow__hover_enabled=\u00bboff\u00bb make_fullwidth__hover=\u00bboff\u00bb make_fullwidth__hover_enabled=\u00bboff\u00bb use_custom_width__hover=\u00bboff\u00bb use_custom_width__hover_enabled=\u00bboff\u00bb width_unit__hover=\u00bbon\u00bb width_unit__hover_enabled=\u00bbon\u00bb make_equal__hover=\u00bboff\u00bb make_equal__hover_enabled=\u00bboff\u00bb use_custom_gutter__hover=\u00bboff\u00bb use_custom_gutter__hover_enabled=\u00bboff\u00bb border_radii__hover=\u00bbon||||\u00bb border_radii__hover_enabled=\u00bbon||||\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb filter_hue_rotate__hover=\u00bb0deg\u00bb filter_hue_rotate__hover_enabled=\u00bb0deg\u00bb filter_saturate__hover=\u00bb100%\u00bb filter_saturate__hover_enabled=\u00bb100%\u00bb filter_brightness__hover=\u00bb100%\u00bb filter_brightness__hover_enabled=\u00bb100%\u00bb filter_contrast__hover=\u00bb100%\u00bb filter_contrast__hover_enabled=\u00bb100%\u00bb filter_invert__hover=\u00bb0%\u00bb filter_invert__hover_enabled=\u00bb0%\u00bb filter_sepia__hover=\u00bb0%\u00bb filter_sepia__hover_enabled=\u00bb0%\u00bb filter_opacity__hover=\u00bb100%\u00bb filter_opacity__hover_enabled=\u00bb100%\u00bb filter_blur__hover=\u00bb0px\u00bb filter_blur__hover_enabled=\u00bb0px\u00bb mix_blend_mode__hover=\u00bbnormal\u00bb mix_blend_mode__hover_enabled=\u00bbnormal\u00bb animation_style__hover=\u00bbnone\u00bb animation_style__hover_enabled=\u00bbnone\u00bb animation_repeat__hover=\u00bbonce\u00bb animation_repeat__hover_enabled=\u00bbonce\u00bb animation_direction__hover=\u00bbcenter\u00bb animation_direction__hover_enabled=\u00bbcenter\u00bb animation_duration__hover=\u00bb1000ms\u00bb animation_duration__hover_enabled=\u00bb1000ms\u00bb animation_delay__hover=\u00bb0ms\u00bb animation_delay__hover_enabled=\u00bb0ms\u00bb animation_intensity_slide__hover=\u00bb50%\u00bb animation_intensity_slide__hover_enabled=\u00bb50%\u00bb animation_intensity_zoom__hover=\u00bb50%\u00bb animation_intensity_zoom__hover_enabled=\u00bb50%\u00bb animation_intensity_flip__hover=\u00bb50%\u00bb animation_intensity_flip__hover_enabled=\u00bb50%\u00bb animation_intensity_fold__hover=\u00bb50%\u00bb animation_intensity_fold__hover_enabled=\u00bb50%\u00bb animation_intensity_roll__hover=\u00bb50%\u00bb animation_intensity_roll__hover_enabled=\u00bb50%\u00bb animation_starting_opacity__hover=\u00bb0%\u00bb animation_starting_opacity__hover_enabled=\u00bb0%\u00bb animation_speed_curve__hover=\u00bbease-in-out\u00bb animation_speed_curve__hover_enabled=\u00bbease-in-out\u00bb hover_transition_duration__hover=\u00bb300ms\u00bb hover_transition_duration__hover_enabled=\u00bb300ms\u00bb hover_transition_delay__hover=\u00bb0ms\u00bb hover_transition_delay__hover_enabled=\u00bb0ms\u00bb hover_transition_speed_curve__hover=\u00bbease\u00bb hover_transition_speed_curve__hover_enabled=\u00bbease\u00bb background_color_gradient_stops__hover=\u00bb#2b87da 0%|#29c4a9 100%\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; custom_width_px__hover=\u00bb1080px\u00bb custom_width_px__hover_enabled=\u00bb1080px\u00bb custom_width_percent__hover=\u00bb80%\u00bb custom_width_percent__hover_enabled=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb parallax_1__hover=\u00bboff\u00bb parallax_1__hover_enabled=\u00bboff\u00bb parallax_2__hover=\u00bboff\u00bb parallax_2__hover_enabled=\u00bboff\u00bb parallax_3__hover=\u00bboff\u00bb parallax_3__hover_enabled=\u00bboff\u00bb parallax_4__hover=\u00bboff\u00bb parallax_4__hover_enabled=\u00bboff\u00bb parallax_method_1__hover=\u00bbon\u00bb parallax_method_1__hover_enabled=\u00bbon\u00bb parallax_method_2__hover=\u00bbon\u00bb parallax_method_2__hover_enabled=\u00bbon\u00bb parallax_method_3__hover=\u00bbon\u00bb parallax_method_3__hover_enabled=\u00bbon\u00bb parallax_method_4__hover=\u00bbon\u00bb parallax_method_4__hover_enabled=\u00bbon\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb make_fullwidth__hover=\u00bboff\u00bb make_fullwidth__hover_enabled=\u00bboff\u00bb use_custom_width__hover=\u00bboff\u00bb use_custom_width__hover_enabled=\u00bboff\u00bb width_unit__hover=\u00bbon\u00bb width_unit__hover_enabled=\u00bbon\u00bb use_custom_gutter__hover=\u00bboff\u00bb use_custom_gutter__hover_enabled=\u00bboff\u00bb make_equal__hover=\u00bboff\u00bb make_equal__hover_enabled=\u00bboff\u00bb border_radii__hover=\u00bbon||||\u00bb border_radii__hover_enabled=\u00bbon||||\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb filter_hue_rotate__hover=\u00bb0deg\u00bb filter_hue_rotate__hover_enabled=\u00bb0deg\u00bb filter_saturate__hover=\u00bb100%\u00bb filter_saturate__hover_enabled=\u00bb100%\u00bb filter_brightness__hover=\u00bb100%\u00bb filter_brightness__hover_enabled=\u00bb100%\u00bb filter_contrast__hover=\u00bb100%\u00bb filter_contrast__hover_enabled=\u00bb100%\u00bb filter_invert__hover=\u00bb0%\u00bb filter_invert__hover_enabled=\u00bb0%\u00bb filter_sepia__hover=\u00bb0%\u00bb filter_sepia__hover_enabled=\u00bb0%\u00bb filter_opacity__hover=\u00bb100%\u00bb filter_opacity__hover_enabled=\u00bb100%\u00bb filter_blur__hover=\u00bb0px\u00bb filter_blur__hover_enabled=\u00bb0px\u00bb mix_blend_mode__hover=\u00bbnormal\u00bb mix_blend_mode__hover_enabled=\u00bbnormal\u00bb animation_style__hover=\u00bbnone\u00bb animation_style__hover_enabled=\u00bbnone\u00bb animation_repeat__hover=\u00bbonce\u00bb animation_repeat__hover_enabled=\u00bbonce\u00bb animation_direction__hover=\u00bbcenter\u00bb animation_direction__hover_enabled=\u00bbcenter\u00bb animation_duration__hover=\u00bb1000ms\u00bb animation_duration__hover_enabled=\u00bb1000ms\u00bb animation_delay__hover=\u00bb0ms\u00bb animation_delay__hover_enabled=\u00bb0ms\u00bb animation_intensity_slide__hover=\u00bb50%\u00bb animation_intensity_slide__hover_enabled=\u00bb50%\u00bb animation_intensity_zoom__hover=\u00bb50%\u00bb animation_intensity_zoom__hover_enabled=\u00bb50%\u00bb animation_intensity_flip__hover=\u00bb50%\u00bb animation_intensity_flip__hover_enabled=\u00bb50%\u00bb animation_intensity_fold__hover=\u00bb50%\u00bb animation_intensity_fold__hover_enabled=\u00bb50%\u00bb animation_intensity_roll__hover=\u00bb50%\u00bb animation_intensity_roll__hover_enabled=\u00bb50%\u00bb animation_starting_opacity__hover=\u00bb0%\u00bb animation_starting_opacity__hover_enabled=\u00bb0%\u00bb animation_speed_curve__hover=\u00bbease-in-out\u00bb animation_speed_curve__hover_enabled=\u00bbease-in-out\u00bb hover_transition_duration__hover=\u00bb300ms\u00bb hover_transition_duration__hover_enabled=\u00bb300ms\u00bb hover_transition_delay__hover=\u00bb0ms\u00bb hover_transition_delay__hover_enabled=\u00bb0ms\u00bb hover_transition_speed_curve__hover=\u00bbease\u00bb hover_transition_speed_curve__hover_enabled=\u00bbease\u00bb background_color_gradient_stops__hover=\u00bb#2b87da 0%|#29c4a9 100%\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bbWork Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbWork Sans|700|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.4em\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb header_font_size__hover=\u00bb30px\u00bb header_font_size__hover_enabled=\u00bb30px\u00bb header_letter_spacing__hover=\u00bb0px\u00bb header_letter_spacing__hover_enabled=\u00bb0px\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb]<\/p>\n<h2 style=\"text-align: justify;\">Sobre Cl\u00ednica del Pie Vara<\/h2>\n<p style=\"text-align: justify;\">Bienvenidos a la Cl\u00ednica del Pie Vara. Con orgullo y pasi\u00f3n, brindamos cuidado podol\u00f3gico excepcional para toda la familia. Nuestro equipo de pod\u00f3logos altamente capacitados y comprometidos se dedica a mejorar la salud y el confort de tus pies.<\/p>\n<p style=\"text-align: justify;\">En la Cl\u00ednica del Pie Vara, fusionamos experiencia y tecnolog\u00eda de vanguardia para ofrecer tratamientos integrales y personalizados. Ya sea que necesites atenci\u00f3n para problemas comunes como hongos en las u\u00f1as, callosidades o dolores en los pies, o requieras cuidados especiales para condiciones m\u00e9dicas m\u00e1s complejas, estamos aqu\u00ed para ayudarte.<\/p>\n<p style=\"text-align: justify;\">Nos enorgullece ser un centro de confianza en el que puedes confiar para tus necesidades podol\u00f3gicas. Nuestra misi\u00f3n es mantener tus pies en movimiento y libres de molestias. Visita nuestra cl\u00ednica y d\u00e9janos cuidar de tus pies para que puedas disfrutar de una vida activa y saludable. Tu bienestar podol\u00f3gico es nuestra prioridad en la Cl\u00ednica del Pie Vara.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/clinicadelpievara.es\/sobre-nosotros\/\u00bb button_text=\u00bbVER M\u00c1S\u00bb button_alignment=\u00bbright\u00bb _builder_version=\u00bb4.21.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#1664ac\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb5px\u00bb button_letter_spacing=\u00bb2px\u00bb button_font=\u00bbWork Sans|600||on|||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb10px|30px|10px|30px|true|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#82ddb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbWhy Us\u00bb _builder_version=\u00bb4.16&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bb#eff9ff 64%|#ffffff 64%\u00bb background_color_gradient_start=\u00bb#eff9ff\u00bb background_color_gradient_start_position=\u00bb64%\u00bb background_color_gradient_end=\u00bb#ffffff\u00bb background_color_gradient_end_position=\u00bb64%\u00bb custom_padding=\u00bb54px|0px|90px|0px|false|false\u00bb custom_width_px__hover=\u00bb1080px\u00bb custom_width_px__hover_enabled=\u00bb1080px\u00bb custom_width_percent__hover=\u00bb80%\u00bb custom_width_percent__hover_enabled=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb gutter_width__hover=\u00bb3&#8243; gutter_width__hover_enabled=\u00bb3&#8243; parallax_1__hover=\u00bboff\u00bb parallax_1__hover_enabled=\u00bboff\u00bb parallax_2__hover=\u00bboff\u00bb parallax_2__hover_enabled=\u00bboff\u00bb parallax_3__hover=\u00bboff\u00bb parallax_3__hover_enabled=\u00bboff\u00bb parallax_method_1__hover=\u00bbon\u00bb parallax_method_1__hover_enabled=\u00bbon\u00bb parallax_method_2__hover=\u00bbon\u00bb parallax_method_2__hover_enabled=\u00bbon\u00bb parallax_method_3__hover=\u00bbon\u00bb parallax_method_3__hover_enabled=\u00bbon\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb inner_shadow__hover=\u00bboff\u00bb inner_shadow__hover_enabled=\u00bboff\u00bb make_fullwidth__hover=\u00bboff\u00bb make_fullwidth__hover_enabled=\u00bboff\u00bb use_custom_width__hover=\u00bboff\u00bb use_custom_width__hover_enabled=\u00bboff\u00bb width_unit__hover=\u00bbon\u00bb width_unit__hover_enabled=\u00bbon\u00bb make_equal__hover=\u00bboff\u00bb make_equal__hover_enabled=\u00bboff\u00bb use_custom_gutter__hover=\u00bboff\u00bb use_custom_gutter__hover_enabled=\u00bboff\u00bb border_radii__hover=\u00bbon||||\u00bb border_radii__hover_enabled=\u00bbon||||\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb filter_hue_rotate__hover=\u00bb0deg\u00bb filter_hue_rotate__hover_enabled=\u00bb0deg\u00bb filter_saturate__hover=\u00bb100%\u00bb filter_saturate__hover_enabled=\u00bb100%\u00bb filter_brightness__hover=\u00bb100%\u00bb filter_brightness__hover_enabled=\u00bb100%\u00bb filter_contrast__hover=\u00bb100%\u00bb filter_contrast__hover_enabled=\u00bb100%\u00bb filter_invert__hover=\u00bb0%\u00bb filter_invert__hover_enabled=\u00bb0%\u00bb filter_sepia__hover=\u00bb0%\u00bb filter_sepia__hover_enabled=\u00bb0%\u00bb filter_opacity__hover=\u00bb100%\u00bb filter_opacity__hover_enabled=\u00bb100%\u00bb filter_blur__hover=\u00bb0px\u00bb filter_blur__hover_enabled=\u00bb0px\u00bb mix_blend_mode__hover=\u00bbnormal\u00bb mix_blend_mode__hover_enabled=\u00bbnormal\u00bb animation_style__hover=\u00bbnone\u00bb animation_style__hover_enabled=\u00bbnone\u00bb animation_repeat__hover=\u00bbonce\u00bb animation_repeat__hover_enabled=\u00bbonce\u00bb animation_direction__hover=\u00bbcenter\u00bb animation_direction__hover_enabled=\u00bbcenter\u00bb animation_duration__hover=\u00bb1000ms\u00bb animation_duration__hover_enabled=\u00bb1000ms\u00bb animation_delay__hover=\u00bb0ms\u00bb animation_delay__hover_enabled=\u00bb0ms\u00bb animation_intensity_slide__hover=\u00bb50%\u00bb animation_intensity_slide__hover_enabled=\u00bb50%\u00bb animation_intensity_zoom__hover=\u00bb50%\u00bb animation_intensity_zoom__hover_enabled=\u00bb50%\u00bb animation_intensity_flip__hover=\u00bb50%\u00bb animation_intensity_flip__hover_enabled=\u00bb50%\u00bb animation_intensity_fold__hover=\u00bb50%\u00bb animation_intensity_fold__hover_enabled=\u00bb50%\u00bb animation_intensity_roll__hover=\u00bb50%\u00bb animation_intensity_roll__hover_enabled=\u00bb50%\u00bb animation_starting_opacity__hover=\u00bb0%\u00bb animation_starting_opacity__hover_enabled=\u00bb0%\u00bb animation_speed_curve__hover=\u00bbease-in-out\u00bb animation_speed_curve__hover_enabled=\u00bbease-in-out\u00bb hover_transition_duration__hover=\u00bb300ms\u00bb hover_transition_duration__hover_enabled=\u00bb300ms\u00bb hover_transition_delay__hover=\u00bb0ms\u00bb hover_transition_delay__hover_enabled=\u00bb0ms\u00bb hover_transition_speed_curve__hover=\u00bbease\u00bb hover_transition_speed_curve__hover_enabled=\u00bbease\u00bb background_color_gradient_stops__hover=\u00bb#2b87da 0%|#29c4a9 100%\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb padding_top_bottom_link_1=\u00bbfalse\u00bb padding_top_bottom_link_2=\u00bbtrue\u00bb padding_left_right_link_1=\u00bbtrue\u00bb padding_left_right_link_2=\u00bbtrue\u00bb _builder_version=\u00bb4.21.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(34,42,137,0) 0%|#1664ac 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(34,42,137,0)\u00bb background_color_gradient_end=\u00bbrgba(34,42,137,0.8)\u00bb background_image=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/health-clinic-34.jpg\u00bb width=\u00bb90%\u00bb max_width=\u00bb90%\u00bb module_alignment=\u00bbleft\u00bb custom_padding=\u00bb0|0px|0px|0px|false|false\u00bb animation_style=\u00bbflip\u00bb animation_direction=\u00bbleft\u00bb border_radii=\u00bb|||120px|\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb42px\u00bb box_shadow_blur=\u00bb108px\u00bb box_shadow_spread=\u00bb-26px\u00bb box_shadow_color=\u00bbrgba(94,137,251,0.64)\u00bb use_custom_width=\u00bbon\u00bb width_unit=\u00bboff\u00bb custom_width_percent=\u00bb90%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb20vw|50px|50px|50px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bbWork Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbWork Sans|700|||||||\u00bb header_2_font_size=\u00bb60px\u00bb header_2_line_height=\u00bb1.2em\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb700px\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb header_font_size__hover=\u00bb30px\u00bb header_font_size__hover_enabled=\u00bb30px\u00bb header_letter_spacing__hover=\u00bb0px\u00bb header_letter_spacing__hover_enabled=\u00bb0px\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb]<\/p>\n<h2>Habla con nosotros<\/h2>\n<p>Si tienes alguna consulta, no dudes en ponerte en contacto con nosotros y te resolveremos todas las dudas.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/clinicadelpievara.es\/contacto\/\u00bb button_text=\u00bbCONTACTAR\u00bb _builder_version=\u00bb4.21.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#103048&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb5px\u00bb button_letter_spacing=\u00bb2px\u00bb button_font=\u00bbWork Sans|600||on|||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb10px|30px|10px|30px|true|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#7a9eff\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.21.0&#8243; background_color=\u00bb#1664ac\u00bb custom_padding=\u00bb100px|100px|100px|100px\u00bb custom_padding_tablet=\u00bb|80px||80px||true\u00bb custom_padding_phone=\u00bb|40px||40px||true\u00bb custom_padding_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb padding_phone=\u00bb|40px||40px||true\u00bb padding_tablet=\u00bb|80px||80px||true\u00bb padding_last_edited=\u00bbon|desktop\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; text_font=\u00bbWork Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.5em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbWork Sans|700|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.2em\u00bb background_layout=\u00bbdark\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb16px\u00bb text_font_size_last_edited=\u00bboff|desktop\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb header_font_size__hover=\u00bb30px\u00bb header_font_size__hover_enabled=\u00bb30px\u00bb header_letter_spacing__hover=\u00bb0px\u00bb header_letter_spacing__hover_enabled=\u00bb0px\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb]<\/p>\n<h2>\u00bfPor qu\u00e9 elegirnos?<\/h2>\n<p>[\/et_pb_text][et_pb_blurb title=\u00bbGran Experiencia\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x4e;||divi||400&#8243; icon_color=\u00bb#ffffff\u00bb image_icon_background_color=\u00bb#103048&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb32px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbWork Sans|600|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbWork Sans||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.8em\u00bb image_icon_custom_padding=\u00bb8px|8px|8px|8px|false|false\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb5px||5px||true\u00bb animation=\u00bboff\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb2px\u00bb border_color_all_image=\u00bbrgba(255,255,255,0)\u00bb icon_font_size=\u00bb32px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(255,255,255,0)\u00bb circle_color=\u00bbrgba(255,255,255,0.24)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb body_line_height__hover=\u00bb1.7em\u00bb body_line_height__hover_enabled=\u00bb1.7em\u00bb image_icon_background_color__sticky_enabled=\u00bb#7EBEC5&#8243; image_icon_background_color__sticky=\u00bb#7EBEC5&#8243;]<\/p>\n<p>Contamos con un largo recorrido profesional que nos permite dar el mejor servicio posible.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbPersonal altamente cualificado\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x4e;||divi||400&#8243; icon_color=\u00bb#ffffff\u00bb image_icon_background_color=\u00bb#103048&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb32px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbWork Sans|600|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbWork Sans||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.8em\u00bb image_icon_custom_padding=\u00bb8px|8px|8px|8px|false|false\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb5px||5px||true\u00bb animation=\u00bboff\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb2px\u00bb border_color_all_image=\u00bbrgba(255,255,255,0)\u00bb icon_font_size=\u00bb32px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(255,255,255,0)\u00bb circle_color=\u00bbrgba(255,255,255,0.24)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb body_line_height__hover=\u00bb1.7em\u00bb body_line_height__hover_enabled=\u00bb1.7em\u00bb body_font_size__hover=\u00bb14px\u00bb body_font_size__hover_enabled=\u00bb14px\u00bb image_icon_background_color__sticky_enabled=\u00bb#7EBEC5&#8243; image_icon_background_color__sticky=\u00bb#7EBEC5&#8243;]<\/p>\n<p>Todo nuestro personal cumple un nivel de exigencia que nos permite ser referentes en el sector.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbTrato cercano y humano\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x4e;||divi||400&#8243; icon_color=\u00bb#ffffff\u00bb image_icon_background_color=\u00bb#103048&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb32px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbWork Sans|600|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbWork Sans||||||||\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.8em\u00bb image_icon_custom_padding=\u00bb8px|8px|8px|8px|false|false\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb5px||5px||true\u00bb animation=\u00bboff\u00bb body_font_size_tablet=\u00bb16px\u00bb body_font_size_phone=\u00bb14px\u00bb body_font_size_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb2px\u00bb border_color_all_image=\u00bbrgba(255,255,255,0)\u00bb icon_font_size=\u00bb32px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(255,255,255,0)\u00bb circle_color=\u00bbrgba(255,255,255,0.24)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb body_line_height__hover=\u00bb1.7em\u00bb body_line_height__hover_enabled=\u00bb1.7em\u00bb body_font_size__hover=\u00bb14px\u00bb body_font_size__hover_enabled=\u00bb14px\u00bb image_icon_background_color__sticky_enabled=\u00bb#7EBEC5&#8243; image_icon_background_color__sticky=\u00bb#7EBEC5&#8243;]<\/p>\n<p>Nuestro material humando es una de las cosas que destacamos y hace que los clientes esten c\u00f3modos en todo momento.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbVideo\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb100px|0px|0|0px|false|false\u00bb custom_padding_tablet=\u00bb0px||\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb background_color_gradient_stops__hover=\u00bb#2b87da 0%|#29c4a9 100%\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.21.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.21.0&#8243; background_image=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/Sin-titulo.png\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/health-clinic-34.jpg\u00bb title_text=\u00bbhealth-clinic-34&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; text_font=\u00bbWork Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbWork Sans|700|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.2em\u00bb header_3_font=\u00bbWork Sans|600|||||||\u00bb header_3_line_height=\u00bb1.2em\u00bb text_font_size_tablet=\u00bb16px\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb22px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb header_3_font_size_tablet=\u00bb20px\u00bb header_3_font_size_phone=\u00bb18px\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb header_font_size__hover=\u00bb30px\u00bb header_font_size__hover_enabled=\u00bb30px\u00bb header_letter_spacing__hover=\u00bb0px\u00bb header_letter_spacing__hover_enabled=\u00bb0px\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_font_size__hover=\u00bb14px\u00bb text_font_size__hover_enabled=\u00bb14px\u00bb text_letter_spacing__hover=\u00bb0px\u00bb text_letter_spacing__hover_enabled=\u00bb0px\u00bb text_line_height__hover=\u00bb1.7em\u00bb text_line_height__hover_enabled=\u00bb1.7em\u00bb text_text_shadow_style__hover=\u00bbnone\u00bb text_text_shadow_style__hover_enabled=\u00bbnone\u00bb text_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb text_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb link_font_size__hover=\u00bb14px\u00bb link_font_size__hover_enabled=\u00bb14px\u00bb link_letter_spacing__hover=\u00bb0px\u00bb link_letter_spacing__hover_enabled=\u00bb0px\u00bb link_line_height__hover=\u00bb1em\u00bb link_line_height__hover_enabled=\u00bb1em\u00bb link_text_shadow_style__hover=\u00bbnone\u00bb link_text_shadow_style__hover_enabled=\u00bbnone\u00bb link_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb link_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ul_font_size__hover=\u00bb14px\u00bb ul_font_size__hover_enabled=\u00bb14px\u00bb ul_letter_spacing__hover=\u00bb0px\u00bb ul_letter_spacing__hover_enabled=\u00bb0px\u00bb ul_line_height__hover=\u00bb1em\u00bb ul_line_height__hover_enabled=\u00bb1em\u00bb ul_text_shadow_style__hover=\u00bbnone\u00bb ul_text_shadow_style__hover_enabled=\u00bbnone\u00bb ul_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ul_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb ol_font_size__hover=\u00bb14px\u00bb ol_font_size__hover_enabled=\u00bb14px\u00bb ol_letter_spacing__hover=\u00bb0px\u00bb ol_letter_spacing__hover_enabled=\u00bb0px\u00bb ol_line_height__hover=\u00bb1em\u00bb ol_line_height__hover_enabled=\u00bb1em\u00bb ol_text_shadow_style__hover=\u00bbnone\u00bb ol_text_shadow_style__hover_enabled=\u00bbnone\u00bb ol_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb ol_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb quote_font_size__hover=\u00bb14px\u00bb quote_font_size__hover_enabled=\u00bb14px\u00bb quote_letter_spacing__hover=\u00bb0px\u00bb quote_letter_spacing__hover_enabled=\u00bb0px\u00bb quote_line_height__hover=\u00bb1em\u00bb quote_line_height__hover_enabled=\u00bb1em\u00bb quote_text_shadow_style__hover=\u00bbnone\u00bb quote_text_shadow_style__hover_enabled=\u00bbnone\u00bb quote_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb quote_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb text_orientation__hover=\u00bbleft\u00bb text_orientation__hover_enabled=\u00bbleft\u00bb background_layout__hover=\u00bblight\u00bb background_layout__hover_enabled=\u00bblight\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb]<\/p>\n<h2 style=\"text-align: left;\">El mejor servicio personalizado para t\u00ed<\/h2>\n<p style=\"text-align: justify;\"><span>En nuestra cl\u00ednica podol\u00f3gica, nos enorgullece brindar un trato personalizado que pone a nuestros pacientes en el centro de todo lo que hacemos. Reconocemos que cada individuo es \u00fanico y merece una atenci\u00f3n especializada que aborde sus necesidades espec\u00edficas. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>Nuestro equipo de profesionales altamente capacitados se dedica a escucharte atentamente, comprender tus preocupaciones y dise\u00f1ar un plan de tratamiento adaptado a ti. Nos esforzamos por crear un ambiente acogedor donde te sientas c\u00f3modo compartiendo tus inquietudes. A medida que avanzamos juntos en tu proceso de cuidado, nuestra atenci\u00f3n personalizada asegura que cada paso que des est\u00e9 respaldado por una atenci\u00f3n integral y genuina. En nuestra cl\u00ednica, no solo cuidamos tus pies, sino tambi\u00e9n la relaci\u00f3n de confianza que construimos contigo.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/10\/LOGO-RED.ES_.jpg\u00bb title_text=\u00bbLOGO RED.ES\u00bb align=\u00bbright\u00bb align_tablet=\u00bbright\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb width_tablet=\u00bb50%\u00bb width_phone=\u00bb45%\u00bb width_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/10\/LOGO-UNION-EUROPEA.jpg\u00bb title_text=\u00bbLOGO UNI\u00d3N EUROPEA\u00bb align_tablet=\u00bb\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb width_tablet=\u00bb50%\u00bb width_phone=\u00bb45%\u00bb width_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><span>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Financiado por la Uni\u00f3n Europea \u2013 NextGenerationEU<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_image src=\u00bbhttps:\/\/clinicadelpievara.es\/wp-content\/uploads\/2023\/08\/LOGO-CLINICA-DEL-PIE-VARA-scaled.jpg\u00bb title_text=\u00bbLOGO CL\u00cdNICA DEL PIE VARA\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbMontserrat|800|||||||\u00bb text_orientation=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; inline_fonts=\u00bbMontserrat\u00bb global_colors_info=\u00bb{}\u00bb content_last_edited=\u00bbon|desktop\u00bb sticky_enabled=\u00bb0&#8243; content_tablet=\u00bb<\/p>\n<p style=%22text-align: center;%22><span style=%22color: #ffffff;%22><strong>2<\/strong><\/span><\/p>\n<h2><strong><span style=%22color: #000000; font-family: Montserrat;%22><\/span><\/strong><\/h2>\n<h3><strong><span style=%22color: #000000; font-family: Montserrat;%22>CONTACTO<\/span><\/strong><\/h3>\n<p><strong><span style=%22color: #000000; font-family: Montserrat;%22><\/span><\/strong><\/p>\n<p style=%22text-align: left;%22><b>\ud83d\udcde <a href=%22tel:+34956252545%22><span class=%22w8qArf%22><span>\u00a0<\/span><\/span><span><span class=%22LrzXr zdqRlf kno-fv%22><span aria-label=%22Llamar al n\u00famero de tel\u00e9fono 956 25 25 45%22>956 25 25 45<\/span><\/span><\/span><\/a><\/b><\/p>\n<p style=%22text-align: left;%22>CITAS SOLO POR TEL\u00c9FONO\u00a0<\/p>\n<p style=%22text-align: left;%22><b>\ud83d\udccd <\/b><a href=%22https:\/\/www.google.com\/maps\/place\/Cl%C3%ADnica+del+Pie+Roberto+Vara\/@36.518094,-6.2835531,17z\/data=!3m1!4b1!4m6!3m5!1s0xd0dd3cd3a8ac2d5:0x1ecd07796979240a!8m2!3d36.518094!4d-6.2809782!16s%2Fg%2F11b75g6cb_?entry=ttu%22>Av. Constituci\u00f3n de 1812, n\u00ba1, Entreplanta B, 11008 C\u00e1diz<\/a><\/p>\n<div class=%22QsDR1c%22>\n<div class=%22wDYxhc%22 data-attrid=%22kc:\/location\/location:address%22 data-md=%221002%22 lang=%22es-ES%22 data-hveid=%22CD8QAA%22 data-ved=%222ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQkCl6BAg_EAA%22>\n<div class=%22Z1hOCe%22>\n<div class=%22zloOqf PZPZlf%22 data-dtype=%22d3ifr%22 data-local-attribute=%22d3adr%22 data-mid=%22\/g\/11b75g6cb_%22 jsdata=%22kMGuHf;_;CZBT7Q%22 data-ved=%222ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQghwoAHoECD8QAQ%22>\n<div class=%22GnGVVe%22><\/div>\n<div jscontroller=%22sc5wWb%22 class=%22GDRHkb%22 data-at=%225%22 data-uid=%221%22 jsaction=%22rcuQ6b:npT2md%22><\/div>\n<div jscontroller=%22sc5wWb%22 class=%22GDRHkb%22 data-at=%222%22 data-uid=%221%22 jsaction=%22rcuQ6b:npT2md%22><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div class=%22wDYxhc%22 data-attrid=%22kc:\/location\/location:hours%22 data-md=%221005%22 lang=%22es-ES%22 data-hveid=%22CDcQAA%22 data-ved=%222ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQkCl6BAg3EAA%22>\n<div jscontroller=%22ncqIyf%22 class=%22zloOqf PZPZlf%22 jsaction=%22rcuQ6b:npT2md%22><\/div>\n<\/div>\n<\/div>\n<p>\u00bb content_phone=\u00bb<\/p>\n<p style=%22text-align: center;%22><span style=%22color: #ffffff;%22><strong>2<\/strong><\/span><\/p>\n<h2><strong><span style=%22color: #000000; font-family: Montserrat;%22><\/span><\/strong><\/h2>\n<h3><strong><span style=%22color: #000000; font-family: Montserrat;%22>CONTACTO<\/span><\/strong><\/h3>\n<p><strong><span style=%22color: #000000; font-family: Montserrat;%22><\/span><\/strong><\/p>\n<p style=%22text-align: left;%22><b>\ud83d\udcde <a href=%22tel:+34956252545%22><span class=%22w8qArf%22><span>\u00a0<\/span><\/span><span><span class=%22LrzXr zdqRlf kno-fv%22><span aria-label=%22Llamar al n\u00famero de tel\u00e9fono 956 25 25 45%22>956 25 25 45<\/span><\/span><\/span><\/a><\/b><\/p>\n<p style=%22text-align: left;%22>CITAS SOLO POR TEL\u00c9FONO\u00a0<\/p>\n<p style=%22text-align: left;%22><b>\ud83d\udccd <\/b><a href=%22https:\/\/www.google.com\/maps\/place\/Cl%C3%ADnica+del+Pie+Roberto+Vara\/@36.518094,-6.2835531,17z\/data=!3m1!4b1!4m6!3m5!1s0xd0dd3cd3a8ac2d5:0x1ecd07796979240a!8m2!3d36.518094!4d-6.2809782!16s%2Fg%2F11b75g6cb_?entry=ttu%22>Av. Constituci\u00f3n de 1812, n\u00ba1, Entreplanta B, 11008 C\u00e1diz<\/a><\/p>\n<div class=%22QsDR1c%22>\n<div class=%22wDYxhc%22 data-attrid=%22kc:\/location\/location:address%22 data-md=%221002%22 lang=%22es-ES%22 data-hveid=%22CD8QAA%22 data-ved=%222ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQkCl6BAg_EAA%22>\n<div class=%22Z1hOCe%22>\n<div class=%22zloOqf PZPZlf%22 data-dtype=%22d3ifr%22 data-local-attribute=%22d3adr%22 data-mid=%22\/g\/11b75g6cb_%22 jsdata=%22kMGuHf;_;CZBT7Q%22 data-ved=%222ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQghwoAHoECD8QAQ%22>\n<div class=%22GnGVVe%22><\/div>\n<div jscontroller=%22sc5wWb%22 class=%22GDRHkb%22 data-at=%225%22 data-uid=%221%22 jsaction=%22rcuQ6b:npT2md%22><\/div>\n<div jscontroller=%22sc5wWb%22 class=%22GDRHkb%22 data-at=%222%22 data-uid=%221%22 jsaction=%22rcuQ6b:npT2md%22><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div class=%22wDYxhc%22 data-attrid=%22kc:\/location\/location:hours%22 data-md=%221005%22 lang=%22es-ES%22 data-hveid=%22CDcQAA%22 data-ved=%222ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQkCl6BAg3EAA%22>\n<div jscontroller=%22ncqIyf%22 class=%22zloOqf PZPZlf%22 jsaction=%22rcuQ6b:npT2md%22><\/div>\n<\/div>\n<\/div>\n<p>\u00ab]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong>2<\/strong><\/span><\/p>\n<h2><strong><span style=\"color: #000000; font-family: Montserrat;\"><\/span><\/strong><\/h2>\n<h3><strong><span style=\"color: #000000; font-family: Montserrat;\">CONTACTO<\/span><\/strong><\/h3>\n<p><strong><span style=\"color: #000000; font-family: Montserrat;\"><\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><b>\ud83d\udcde <a href=\"tel:+34956252545\"><span class=\"w8qArf\"><span>\u00a0<\/span><\/span><span><span class=\"LrzXr zdqRlf kno-fv\"><span aria-label=\"Llamar al n\u00famero de tel\u00e9fono 956 25 25 45\">956 25 25 45<\/span><\/span><\/span><\/a><\/b><\/p>\n<p style=\"text-align: left;\">CITAS SOLO POR TEL\u00c9FONO\u00a0<\/p>\n<p style=\"text-align: left;\"><b>\ud83d\udccd <\/b><a href=\"https:\/\/www.google.com\/maps\/place\/Cl%C3%ADnica+del+Pie+Roberto+Vara\/@36.518094,-6.2835531,17z\/data=!3m1!4b1!4m6!3m5!1s0xd0dd3cd3a8ac2d5:0x1ecd07796979240a!8m2!3d36.518094!4d-6.2809782!16s%2Fg%2F11b75g6cb_?entry=ttu\">Av. Constituci\u00f3n de 1812, n\u00ba1, Entreplanta B, 11008 C\u00e1diz<\/a><\/p>\n<div class=\"QsDR1c\">\n<div class=\"wDYxhc\" data-attrid=\"kc:\/location\/location:address\" data-md=\"1002\" lang=\"es-ES\" data-hveid=\"CD8QAA\" data-ved=\"2ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQkCl6BAg_EAA\">\n<div class=\"Z1hOCe\">\n<div class=\"zloOqf PZPZlf\" data-dtype=\"d3ifr\" data-local-attribute=\"d3adr\" data-mid=\"\/g\/11b75g6cb_\" jsdata=\"kMGuHf;_;CZBT7Q\" data-ved=\"2ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQghwoAHoECD8QAQ\">\n<div class=\"GnGVVe\"><\/div>\n<div jscontroller=\"sc5wWb\" class=\"GDRHkb\" data-at=\"5\" data-uid=\"1\" jsaction=\"rcuQ6b:npT2md\"><\/div>\n<div jscontroller=\"sc5wWb\" class=\"GDRHkb\" data-at=\"2\" data-uid=\"1\" jsaction=\"rcuQ6b:npT2md\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div class=\"wDYxhc\" data-attrid=\"kc:\/location\/location:hours\" data-md=\"1005\" lang=\"es-ES\" data-hveid=\"CDcQAA\" data-ved=\"2ahUKEwjlhrjDzIGBAxVySPEDHaEXDhIQkCl6BAg3EAA\">\n<div jscontroller=\"ncqIyf\" class=\"zloOqf PZPZlf\" jsaction=\"rcuQ6b:npT2md\"><\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; min_height=\u00bb113.8px\u00bb custom_margin=\u00bb||-82px|||\u00bb custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Dise\u00f1ado por <a href=\"https:\/\/www.eticonsa.es\/\">Eticonsa Inform\u00e1tica<\/a><\/p>\n<p>[\/et_pb_fullwidth_header][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CL\u00cdNICA DEL PIE VARA Caminando juntos hacia la salud de tus pies: Cuidado, cercan\u00eda y confianza en cada paso.Av. Constituci\u00f3n de 1812, n\u00ba1, Entreplanta B, 11008 C\u00e1dizCONTACTO Estamos aqu\u00ed para cuidar de la salud de tus pies. Cont\u00e1ctanos y da el primer paso hacia el bienestar podol\u00f3gico.956 25 25 45Sobre Cl\u00ednica del Pie Vara Bienvenidos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-70","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podolog\u00eda en C\u00e1diz - Clinica del pie Vara Cadiz<\/title>\n<meta name=\"description\" content=\"Cl\u00ednica del Pie en C\u00e1diz. Nuestra cl\u00ednica del pie Vara, cuenta con los mejores profesionales para ofrecer una calidad y servicio excelente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadelpievara.es\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podolog\u00eda en C\u00e1diz - Clinica del pie Vara Cadiz\" \/>\n<meta property=\"og:description\" content=\"Cl\u00ednica del Pie en C\u00e1diz. Nuestra cl\u00ednica del pie Vara, cuenta con los mejores profesionales para ofrecer una calidad y servicio excelente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadelpievara.es\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinica del pie Vara Cadiz\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-26T11:41:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadelpievara.es\\\/\",\"url\":\"https:\\\/\\\/clinicadelpievara.es\\\/\",\"name\":\"Podolog\u00eda en C\u00e1diz - Clinica del pie Vara Cadiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadelpievara.es\\\/#website\"},\"datePublished\":\"2023-08-16T07:38:57+00:00\",\"dateModified\":\"2025-12-26T11:41:33+00:00\",\"description\":\"Cl\u00ednica del Pie en C\u00e1diz. Nuestra cl\u00ednica del pie Vara, cuenta con los mejores profesionales para ofrecer una calidad y servicio excelente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadelpievara.es\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadelpievara.es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadelpievara.es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadelpievara.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INICIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadelpievara.es\\\/#website\",\"url\":\"https:\\\/\\\/clinicadelpievara.es\\\/\",\"name\":\"Clinica del pie Vara Cadiz\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadelpievara.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podolog\u00eda en C\u00e1diz - Clinica del pie Vara Cadiz","description":"Cl\u00ednica del Pie en C\u00e1diz. Nuestra cl\u00ednica del pie Vara, cuenta con los mejores profesionales para ofrecer una calidad y servicio excelente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadelpievara.es\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Podolog\u00eda en C\u00e1diz - Clinica del pie Vara Cadiz","og_description":"Cl\u00ednica del Pie en C\u00e1diz. Nuestra cl\u00ednica del pie Vara, cuenta con los mejores profesionales para ofrecer una calidad y servicio excelente.","og_url":"https:\/\/clinicadelpievara.es\/en\/","og_site_name":"Clinica del pie Vara Cadiz","article_modified_time":"2025-12-26T11:41:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicadelpievara.es\/","url":"https:\/\/clinicadelpievara.es\/","name":"Podolog\u00eda en C\u00e1diz - Clinica del pie Vara Cadiz","isPartOf":{"@id":"https:\/\/clinicadelpievara.es\/#website"},"datePublished":"2023-08-16T07:38:57+00:00","dateModified":"2025-12-26T11:41:33+00:00","description":"Cl\u00ednica del Pie en C\u00e1diz. Nuestra cl\u00ednica del pie Vara, cuenta con los mejores profesionales para ofrecer una calidad y servicio excelente.","breadcrumb":{"@id":"https:\/\/clinicadelpievara.es\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadelpievara.es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadelpievara.es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadelpievara.es\/"},{"@type":"ListItem","position":2,"name":"INICIO"}]},{"@type":"WebSite","@id":"https:\/\/clinicadelpievara.es\/#website","url":"https:\/\/clinicadelpievara.es\/","name":"Clinica del pie Vara Cadiz","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadelpievara.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/pages\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":48,"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/pages\/70\/revisions"}],"predecessor-version":[{"id":459,"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/pages\/70\/revisions\/459"}],"wp:attachment":[{"href":"https:\/\/clinicadelpievara.es\/en\/wp-json\/wp\/v2\/media?parent=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}